{"id":17854,"count":6,"description":"","link":"https:\/\/www.intoxicatedonlife.com\/store\/product-category\/homeschooling\/science\/earth-science-explored\/","name":"Middle School Earth Science","slug":"earth-science-explored","taxonomy":"product_cat","parent":164,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Middle School Earth Science Archives - Intoxicated on Life Store<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intoxicatedonlife.com\/store\/product-category\/homeschooling\/science\/earth-science-explored\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Middle School Earth Science Archives - Intoxicated on Life Store\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intoxicatedonlife.com\/store\/product-category\/homeschooling\/science\/earth-science-explored\/\" \/>\n<meta property=\"og:site_name\" content=\"Intoxicated on Life Store\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.intoxicatedonlife.com\\\/store\\\/product-category\\\/homeschooling\\\/science\\\/earth-science-explored\\\/\",\"url\":\"https:\\\/\\\/www.intoxicatedonlife.com\\\/store\\\/product-category\\\/homeschooling\\\/science\\\/earth-science-explored\\\/\",\"name\":\"Middle School Earth Science Archives - Intoxicated on Life Store\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.intoxicatedonlife.com\\\/store\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.intoxicatedonlife.com\\\/store\\\/product-category\\\/homeschooling\\\/science\\\/earth-science-explored\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.intoxicatedonlife.com\\\/store\\\/product-category\\\/homeschooling\\\/science\\\/earth-science-explored\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.intoxicatedonlife.com\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homeschooling\",\"item\":\"https:\\\/\\\/www.intoxicatedonlife.com\\\/store\\\/product-category\\\/homeschooling\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Science\",\"item\":\"https:\\\/\\\/www.intoxicatedonlife.com\\\/store\\\/product-category\\\/homeschooling\\\/science\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Middle School Earth Science\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.intoxicatedonlife.com\\\/store\\\/#website\",\"url\":\"https:\\\/\\\/www.intoxicatedonlife.com\\\/store\\\/\",\"name\":\"Intoxicated on Life Store\",\"description\":\"Resources for Raising Strong Families\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.intoxicatedonlife.com\\\/store\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Middle School Earth Science Archives - Intoxicated on Life Store","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intoxicatedonlife.com\/store\/product-category\/homeschooling\/science\/earth-science-explored\/","og_locale":"en_US","og_type":"article","og_title":"Middle School Earth Science Archives - Intoxicated on Life Store","og_url":"https:\/\/www.intoxicatedonlife.com\/store\/product-category\/homeschooling\/science\/earth-science-explored\/","og_site_name":"Intoxicated on Life Store","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.intoxicatedonlife.com\/store\/product-category\/homeschooling\/science\/earth-science-explored\/","url":"https:\/\/www.intoxicatedonlife.com\/store\/product-category\/homeschooling\/science\/earth-science-explored\/","name":"Middle School Earth Science Archives - Intoxicated on Life Store","isPartOf":{"@id":"https:\/\/www.intoxicatedonlife.com\/store\/#website"},"breadcrumb":{"@id":"https:\/\/www.intoxicatedonlife.com\/store\/product-category\/homeschooling\/science\/earth-science-explored\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.intoxicatedonlife.com\/store\/product-category\/homeschooling\/science\/earth-science-explored\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intoxicatedonlife.com\/store\/"},{"@type":"ListItem","position":2,"name":"Homeschooling","item":"https:\/\/www.intoxicatedonlife.com\/store\/product-category\/homeschooling\/"},{"@type":"ListItem","position":3,"name":"Science","item":"https:\/\/www.intoxicatedonlife.com\/store\/product-category\/homeschooling\/science\/"},{"@type":"ListItem","position":4,"name":"Middle School Earth Science"}]},{"@type":"WebSite","@id":"https:\/\/www.intoxicatedonlife.com\/store\/#website","url":"https:\/\/www.intoxicatedonlife.com\/store\/","name":"Intoxicated on Life Store","description":"Resources for Raising Strong Families","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intoxicatedonlife.com\/store\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.intoxicatedonlife.com\/store\/wp-json\/wp\/v2\/product_cat\/17854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intoxicatedonlife.com\/store\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.intoxicatedonlife.com\/store\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.intoxicatedonlife.com\/store\/wp-json\/wp\/v2\/product_cat\/164"}],"wp:post_type":[{"href":"https:\/\/www.intoxicatedonlife.com\/store\/wp-json\/wp\/v2\/product?product_cat=17854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}